{"id":3152,"date":"2019-08-27T16:18:31","date_gmt":"2019-08-27T07:18:31","guid":{"rendered":"http:\/\/blogs.stmaur.ac.jp\/fsk\/?p=3152"},"modified":"2019-09-02T10:17:21","modified_gmt":"2019-09-02T01:17:21","slug":"devoirs-de-la-semaine","status":"publish","type":"post","link":"https:\/\/blogs.stmaur.ac.jp\/fsk\/2019\/08\/27\/devoirs-de-la-semaine\/","title":{"rendered":"Devoirs de la semaine"},"content":{"rendered":"<ul>\n<li>Pour <strong><span style=\"color: #ff0000;\">mercredi<\/span><\/strong>, apprendre les 4 1er vers de la po\u00e9sie (Cahier de po\u00e9sie).<\/li>\n<\/ul>\n<p>Les \u00e9l\u00e8ves ont choisi leur po\u00e9sie pr\u00e9f\u00e9r\u00e9e parmi plusieurs possibilit\u00e9s. Les 4 vers ont \u00e9t\u00e9 r\u00e9p\u00e9t\u00e9s en classe. Il s&#8217;agit de travailler la m\u00e9morisation, l&#8217;articulation, l&#8217;intonation tout autant que \u00a0l&#8217;expression corporelle et l&#8217;imagination afin, mardi prochain, lors du concours de po\u00e9sies, de proposer un v\u00e9ritable petit spectacle ! Quant \u00e0 l&#8217;illustration, puisqu&#8217;il y a une semaine pour l&#8217;effectuer, une extr\u00eame application est attendue.<\/p>\n<ul>\n<li>Pour<strong><span style=\"color: #008000;\"> jeudi<\/span><\/strong>, CP apprendre les 6 1er vers et commencer l&#8217;illustration<span style=\"line-height: 1.5;\">\u00a0, CE1 apprendre les 8 1er vers et commencer l&#8217;illustration.<\/span><\/li>\n<li>Pour <strong><span style=\"color: #ff6600;\">vendredi<\/span><\/strong>,\u00a0CP apprendre les 10 1er vers et poursuivre l&#8217;illustration<span style=\"line-height: 1.5;\">\u00a0, CE1 apprendre les 12 1er vers et poursuivre l&#8217;illustration.<\/span><\/li>\n<li>Pour lundi 1) Illustration \u00e0 finir et po\u00e9sie \u00e0 savoir en entier.<\/li>\n<\/ul>\n<p>2) Ma premi\u00e8re semaine (Cahier mes apprentissages, mes objectifs)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour mercredi, apprendre les 4 1er vers de la po\u00e9sie (Cahier de po\u00e9sie). Les \u00e9l\u00e8ves ont choisi leur po\u00e9sie pr\u00e9f\u00e9r\u00e9e parmi plusieurs possibilit\u00e9s. Les 4 vers ont \u00e9t\u00e9 r\u00e9p\u00e9t\u00e9s en classe. Il s&#8217;agit de travailler la m\u00e9morisation, l&#8217;articulation, l&#8217;intonation tout autant que \u00a0l&#8217;expression corporelle et l&#8217;imagination afin, mardi prochain, lors du concours de po\u00e9sies, de&#8230; <a href=\"https:\/\/blogs.stmaur.ac.jp\/fsk\/2019\/08\/27\/devoirs-de-la-semaine\/\">Read more: Devoirs de la semaine<\/a><\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3152","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.stmaur.ac.jp\/fsk\/wp-json\/wp\/v2\/posts\/3152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.stmaur.ac.jp\/fsk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.stmaur.ac.jp\/fsk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.stmaur.ac.jp\/fsk\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.stmaur.ac.jp\/fsk\/wp-json\/wp\/v2\/comments?post=3152"}],"version-history":[{"count":2,"href":"https:\/\/blogs.stmaur.ac.jp\/fsk\/wp-json\/wp\/v2\/posts\/3152\/revisions"}],"predecessor-version":[{"id":3181,"href":"https:\/\/blogs.stmaur.ac.jp\/fsk\/wp-json\/wp\/v2\/posts\/3152\/revisions\/3181"}],"wp:attachment":[{"href":"https:\/\/blogs.stmaur.ac.jp\/fsk\/wp-json\/wp\/v2\/media?parent=3152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.stmaur.ac.jp\/fsk\/wp-json\/wp\/v2\/categories?post=3152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.stmaur.ac.jp\/fsk\/wp-json\/wp\/v2\/tags?post=3152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}