{"id":1006,"date":"2017-04-04T14:36:47","date_gmt":"2017-04-04T05:36:47","guid":{"rendered":"http:\/\/blogs.stmaur.ac.jp\/fsk\/?p=1006"},"modified":"2017-04-04T14:36:47","modified_gmt":"2017-04-04T05:36:47","slug":"bien-se-concentrer-pour-bien-ecrire","status":"publish","type":"post","link":"https:\/\/blogs.stmaur.ac.jp\/fsk\/2017\/04\/04\/bien-se-concentrer-pour-bien-ecrire\/","title":{"rendered":"Bien se concentrer  pour bien \u00e9crire !"},"content":{"rendered":"<p><a href=\"http:\/\/blogs.stmaur.ac.jp\/fsk\/files\/2017\/04\/ecris-1m1rvdq.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-1007\" src=\"http:\/\/blogs.stmaur.ac.jp\/fsk\/files\/2017\/04\/ecris-1m1rvdq-300x224.png\" alt=\"\" width=\"263\" height=\"196\" srcset=\"https:\/\/blogs.stmaur.ac.jp\/fsk\/files\/2017\/04\/ecris-1m1rvdq-300x224.png 300w, https:\/\/blogs.stmaur.ac.jp\/fsk\/files\/2017\/04\/ecris-1m1rvdq-768x574.png 768w, https:\/\/blogs.stmaur.ac.jp\/fsk\/files\/2017\/04\/ecris-1m1rvdq-1024x765.png 1024w, https:\/\/blogs.stmaur.ac.jp\/fsk\/files\/2017\/04\/ecris-1m1rvdq.png 1217w\" sizes=\"auto, (max-width: 263px) 100vw, 263px\" \/><\/a><\/p>\n<p>Est-ce que nous sommes en train de dormir ? Non, nous nous relaxons, nous nous d\u00e9tendons, nous faisons travailler notre imagination et notre m\u00e9moire pour <strong><span style=\"color: #008000;\">cr\u00e9er une histoire<\/span><\/strong>. Les CE1 sont d\u00e9j\u00e0 bien habitu\u00e9s, mais pour nous \u00a0les CP, c&#8217;est la premi\u00e8re fois. Nous \u00e9crivons et lisons suffisamment bien maintenant pour le faire. Que c&#8217;est excitant! Rendez-vous la semaine prochaine pour la lecture de nos oeuvres dont le th\u00e8me est le suivant : <strong><span style=\"color: #008000;\">nos vacances<\/span> <\/strong>!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est-ce que nous sommes en train de dormir ? Non, nous nous relaxons, nous nous d\u00e9tendons, nous faisons travailler notre imagination et notre m\u00e9moire pour cr\u00e9er une histoire. Les CE1 sont d\u00e9j\u00e0 bien habitu\u00e9s, mais pour nous \u00a0les CP, c&#8217;est la premi\u00e8re fois. Nous \u00e9crivons et lisons suffisamment bien maintenant pour le faire. Que c&#8217;est&#8230; <a href=\"https:\/\/blogs.stmaur.ac.jp\/fsk\/2017\/04\/04\/bien-se-concentrer-pour-bien-ecrire\/\">Read more: Bien se concentrer  pour bien \u00e9crire !<\/a><\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1006","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/blogs.stmaur.ac.jp\/fsk\/wp-json\/wp\/v2\/posts\/1006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.stmaur.ac.jp\/fsk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.stmaur.ac.jp\/fsk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.stmaur.ac.jp\/fsk\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.stmaur.ac.jp\/fsk\/wp-json\/wp\/v2\/comments?post=1006"}],"version-history":[{"count":1,"href":"https:\/\/blogs.stmaur.ac.jp\/fsk\/wp-json\/wp\/v2\/posts\/1006\/revisions"}],"predecessor-version":[{"id":1008,"href":"https:\/\/blogs.stmaur.ac.jp\/fsk\/wp-json\/wp\/v2\/posts\/1006\/revisions\/1008"}],"wp:attachment":[{"href":"https:\/\/blogs.stmaur.ac.jp\/fsk\/wp-json\/wp\/v2\/media?parent=1006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.stmaur.ac.jp\/fsk\/wp-json\/wp\/v2\/categories?post=1006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.stmaur.ac.jp\/fsk\/wp-json\/wp\/v2\/tags?post=1006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}